{"id":2530,"date":"2025-10-27T21:22:00","date_gmt":"2025-10-27T14:22:00","guid":{"rendered":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/?p=2530"},"modified":"2026-03-24T21:29:42","modified_gmt":"2026-03-24T14:29:42","slug":"a-memorial-service-for-her-majesty-queen-sirikit-the-queen-mother","status":"publish","type":"post","link":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/cabnews\/27102025-a-memorial-service-for-her-majesty-queen-sirikit-the-queen-mother\/","title":{"rendered":"\u0e1e\u0e34\u0e18\u0e35\u0e19\u0e49\u0e2d\u0e21\u0e16\u0e27\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e32\u0e25\u0e31\u0e22 \u0e41\u0e14\u0e48\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e19\u0e32\u0e07\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e01\u0e34\u0e15\u0e34\u0e4c \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e34\u0e19\u0e35\u0e19\u0e32\u0e16 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35\u0e1e\u0e31\u0e19\u0e1b\u0e35\u0e2b\u0e25\u0e27\u0e07"},"content":{"rendered":"\n<p>\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e19\u0e49\u0e2d\u0e21\u0e16\u0e27\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e32\u0e25\u0e31\u0e22\u0e41\u0e14\u0e48 \u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e19\u0e32\u0e07\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e01\u0e34\u0e15\u0e34\u0e4c \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e34\u0e19\u0e35\u0e19\u0e32\u0e16 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35\u0e1e\u0e31\u0e19\u0e1b\u0e35\u0e2b\u0e25\u0e27\u0e07 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 27 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21 2568 \u0e40\u0e27\u0e25\u0e32 09.15 &#8211; 10.00 \u0e19. \u0e14\u0e23.\u0e2d\u0e23\u0e2d\u0e38\u0e1a\u0e25 \u0e0a\u0e21\u0e40\u0e14\u0e0a \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e02\u0e2d\u0e07\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e2f \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e19\u0e49\u0e2d\u0e21\u0e16\u0e27\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e32\u0e25\u0e31\u0e22 \u0e41\u0e14\u0e48\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e19\u0e32\u0e07\u0e40\u0e08\u0e49\u0e32 \u0e2a\u0e34\u0e23\u0e34\u0e01\u0e34\u0e15\u0e34\u0e4c \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e34\u0e19\u0e35\u0e19\u0e32\u0e16 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35\u0e1e\u0e31\u0e19\u0e1b\u0e35\u0e2b\u0e25\u0e27\u0e07 \u0e17\u0e35\u0e48\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e41\u0e2a\u0e19 \u0e08\u0e31\u0e14\u0e02\u0e36\u0e49\u0e19 \u0e13 \u0e25\u0e32\u0e19\u0e40\u0e2d\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u0e0a\u0e31\u0e49\u0e19 1 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2b\u0e25\u0e27\u0e07\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e27\u0e32\u0e08\u0e01\u0e01\u0e2a\u0e34\u0e01\u0e34\u0e08 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e41\u0e2a\u0e19 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e19\u0e35\u0e49 \u0e23\u0e28.\u0e19.\u0e2a\u0e1e.\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e0a\u0e31\u0e22 \u0e20\u0e34\u0e0d\u0e42\u0e0d\u0e20\u0e39\u0e21\u0e34\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e23\u0e2d\u0e07\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e41\u0e2a\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e43\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e23\u0e32\u0e1a\u0e16\u0e27\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e32\u0e25\u0e31\u0e22 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e48\u0e27\u0e19\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e19\u0e34\u0e2a\u0e34\u0e15 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e1e\u0e23\u0e35\u0e22\u0e07\u0e01\u0e31\u0e19\u0e23\u0e48\u0e27\u0e21\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e32\u0e25\u0e31\u0e22 \u0e22\u0e37\u0e19\u0e2a\u0e07\u0e1a\u0e19\u0e34\u0e48\u0e07\u0e19\u0e49\u0e2d\u0e21\u0e23\u0e33\u0e25\u0e36\u0e01\u0e43\u0e19\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e32\u0e01\u0e23\u0e38\u0e13\u0e32\u0e18\u0e34\u0e04\u0e38\u0e13\u0e2d\u0e31\u0e19\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e21\u0e34\u0e44\u0e14\u0e49 \u0e41\u0e25\u0e30\u0e25\u0e07\u0e19\u0e32\u0e21\u0e16\u0e27\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e32\u0e25\u0e31\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e1e\u0e23\u0e30\u0e09\u0e32\u0e22\u0e32\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u00a0<\/p>\n\n\n\n<div aria-label=\"Carousel Gallery\" class=\"wp-block-coblocks-gallery-carousel\"><div class=\"coblocks-gallery-carousel-swiper-container is-cropped coblocks-gallery has-no-alignment has-border-radius-10 has-caption-style-dark has-horizontal-gutter has-lightbox has-no-thumbnails\"><div class=\"has-carousel has-carousel-lrg swiper-container\" data-swiper=\"{&quot;alignCells&quot;:false,&quot;autoPlay&quot;:true,&quot;autoPlaySpeed&quot;:3000,&quot;draggable&quot;:true,&quot;freeMode&quot;:false,&quot;loop&quot;:true,&quot;navigation&quot;:true,&quot;pageDots&quot;:false,&quot;pauseHover&quot;:false,&quot;responsiveHeight&quot;:false,&quot;slidesPerView&quot;:2,&quot;thumbnails&quot;:false,&quot;uuid&quot;:&quot;12345&quot;}\" style=\"height:500px\"><div class=\"swiper-wrapper\"><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\" tabindex=\"0\"><figure class=\"coblocks-gallery--figure has-margin-left-10 has-margin-right-10\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" alt=\"\" class=\"wp-image-2541\" data-id=\"2541\" data-link=\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/?attachment_id=2541\" src=\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-content\/uploads\/2026\/03\/DSC01020.jpg\" srcset=\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-content\/uploads\/2026\/03\/DSC01020.jpg 1024w, https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-content\/uploads\/2026\/03\/DSC01020-300x225.jpg 300w, https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-content\/uploads\/2026\/03\/DSC01020-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\" tabindex=\"1\"><figure class=\"coblocks-gallery--figure has-margin-left-10 has-margin-right-10\"><img decoding=\"async\" width=\"1024\" height=\"768\" alt=\"\" class=\"wp-image-2538\" data-id=\"2538\" data-link=\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/?attachment_id=2538\" src=\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-content\/uploads\/2026\/03\/DSC01041.jpg\" srcset=\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-content\/uploads\/2026\/03\/DSC01041.jpg 1024w, https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-content\/uploads\/2026\/03\/DSC01041-300x225.jpg 300w, https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-content\/uploads\/2026\/03\/DSC01041-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\" tabindex=\"2\"><figure class=\"coblocks-gallery--figure has-margin-left-10 has-margin-right-10\"><img decoding=\"async\" width=\"1024\" height=\"768\" alt=\"\" class=\"wp-image-2543\" data-id=\"2543\" data-link=\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/?attachment_id=2543\" src=\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-content\/uploads\/2026\/03\/DSC00906.jpg\" srcset=\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-content\/uploads\/2026\/03\/DSC00906.jpg 1024w, https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-content\/uploads\/2026\/03\/DSC00906-300x225.jpg 300w, https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-content\/uploads\/2026\/03\/DSC00906-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\" tabindex=\"3\"><figure class=\"coblocks-gallery--figure has-margin-left-10 has-margin-right-10\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" alt=\"\" class=\"wp-image-2542\" data-id=\"2542\" data-link=\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/?attachment_id=2542\" src=\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-content\/uploads\/2026\/03\/DSC00982.jpg\" srcset=\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-content\/uploads\/2026\/03\/DSC00982.jpg 1024w, https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-content\/uploads\/2026\/03\/DSC00982-300x225.jpg 300w, https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-content\/uploads\/2026\/03\/DSC00982-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\" tabindex=\"4\"><figure class=\"coblocks-gallery--figure has-margin-left-10 has-margin-right-10\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" alt=\"\" class=\"wp-image-2539\" data-id=\"2539\" data-link=\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/?attachment_id=2539\" src=\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-content\/uploads\/2026\/03\/DSC01027.jpg\" srcset=\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-content\/uploads\/2026\/03\/DSC01027.jpg 1024w, https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-content\/uploads\/2026\/03\/DSC01027-300x225.jpg 300w, https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-content\/uploads\/2026\/03\/DSC01027-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\" tabindex=\"5\"><figure class=\"coblocks-gallery--figure has-margin-left-10 has-margin-right-10\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" alt=\"\" class=\"wp-image-2540\" data-id=\"2540\" data-link=\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/?attachment_id=2540\" src=\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-content\/uploads\/2026\/03\/DSC01021.jpg\" srcset=\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-content\/uploads\/2026\/03\/DSC01021.jpg 1024w, https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-content\/uploads\/2026\/03\/DSC01021-300x225.jpg 300w, https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-content\/uploads\/2026\/03\/DSC01021-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><\/div><button class=\"nav-button__prev\" id=\"12345-prev\"><svg class=\"icon\" style=\"transform:rotate(180deg)\"><\/svg><\/button><button class=\"nav-button__next\" id=\"12345-next\"><svg class=\"icon\"><\/svg><\/button><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e19\u0e49\u0e2d\u0e21\u0e16\u0e27\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e32\u0e25\u0e31\u0e22\u0e41\u0e14\u0e48 \u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e19\u0e32\u0e07\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e01\u0e34\u0e15\u0e34\u0e4c \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e34\u0e19\u0e35\u0e19\u0e32\u0e16 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35\u0e1e\u0e31\u0e19\u0e1b\u0e35\u0e2b\u0e25\u0e27\u0e07 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 27 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21 2568 \u0e40\u0e27\u0e25\u0e32 09.15 &#8211; 10.00 \u0e19. \u0e14\u0e23.\u0e2d\u0e23\u0e2d\u0e38\u0e1a\u0e25 \u0e0a\u0e21\u0e40\u0e14\u0e0a \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e02\u0e2d\u0e07\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e2f \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e19\u0e49\u0e2d\u0e21\u0e16\u0e27\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e32\u0e25\u0e31\u0e22 \u0e41\u0e14\u0e48\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e19\u0e32\u0e07\u0e40\u0e08\u0e49\u0e32 \u0e2a\u0e34\u0e23\u0e34\u0e01\u0e34\u0e15\u0e34\u0e4c \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e34\u0e19\u0e35\u0e19\u0e32\u0e16 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35\u0e1e\u0e31\u0e19\u0e1b\u0e35\u0e2b\u0e25\u0e27\u0e07 \u0e17\u0e35\u0e48\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e41\u0e2a\u0e19 \u0e08\u0e31\u0e14\u0e02\u0e36\u0e49\u0e19 \u0e13 \u0e25\u0e32\u0e19\u0e40\u0e2d\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u0e0a\u0e31\u0e49\u0e19 1 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2b\u0e25\u0e27\u0e07\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e27\u0e32\u0e08\u0e01\u0e01\u0e2a\u0e34\u0e01\u0e34\u0e08 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e41\u0e2a\u0e19 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e19\u0e35\u0e49 \u0e23\u0e28.\u0e19.\u0e2a\u0e1e.\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e0a\u0e31\u0e22 \u0e20\u0e34\u0e0d\u0e42\u0e0d\u0e20\u0e39\u0e21\u0e34\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e23\u0e2d\u0e07\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e41\u0e2a\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e43\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e23\u0e32\u0e1a\u0e16\u0e27\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e32\u0e25\u0e31\u0e22 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e48\u0e27\u0e19\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e19\u0e34\u0e2a\u0e34\u0e15 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e1e\u0e23\u0e35\u0e22\u0e07\u0e01\u0e31\u0e19\u0e23\u0e48\u0e27\u0e21\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e32\u0e25\u0e31\u0e22 \u0e22\u0e37\u0e19\u0e2a\u0e07\u0e1a\u0e19\u0e34\u0e48\u0e07\u0e19\u0e49\u0e2d\u0e21\u0e23\u0e33\u0e25\u0e36\u0e01\u0e43\u0e19\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e32\u0e01\u0e23\u0e38\u0e13\u0e32\u0e18\u0e34\u0e04\u0e38\u0e13\u0e2d\u0e31\u0e19\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e21\u0e34\u0e44\u0e14\u0e49 \u0e41\u0e25\u0e30\u0e25\u0e07\u0e19\u0e32\u0e21\u0e16\u0e27\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e32\u0e25\u0e31\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e1e\u0e23\u0e30\u0e09\u0e32\u0e22\u0e32\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u00a0<\/p>\n","protected":false},"author":1,"featured_media":2541,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[49,1],"tags":[],"class_list":["post-2530","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-royal-honor","category-cabnews"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.5 (Yoast SEO v27.1.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u0e1e\u0e34\u0e18\u0e35\u0e19\u0e49\u0e2d\u0e21\u0e16\u0e27\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e32\u0e25\u0e31\u0e22 \u0e41\u0e14\u0e48\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e19\u0e32\u0e07\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e01\u0e34\u0e15\u0e34\u0e4c \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e34\u0e19\u0e35\u0e19\u0e32\u0e16 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35\u0e1e\u0e31\u0e19\u0e1b\u0e35\u0e2b\u0e25\u0e27\u0e07 - cab.ku<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/cabnews\/27102025-a-memorial-service-for-her-majesty-queen-sirikit-the-queen-mother\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e1e\u0e34\u0e18\u0e35\u0e19\u0e49\u0e2d\u0e21\u0e16\u0e27\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e32\u0e25\u0e31\u0e22 \u0e41\u0e14\u0e48\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e19\u0e32\u0e07\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e01\u0e34\u0e15\u0e34\u0e4c \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e34\u0e19\u0e35\u0e19\u0e32\u0e16 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35\u0e1e\u0e31\u0e19\u0e1b\u0e35\u0e2b\u0e25\u0e27\u0e07\" \/>\n<meta property=\"og:description\" content=\"\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e19\u0e49\u0e2d\u0e21\u0e16\u0e27\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e32\u0e25\u0e31\u0e22\u0e41\u0e14\u0e48 \u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e19\u0e32\u0e07\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e01\u0e34\u0e15\u0e34\u0e4c \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e34\u0e19\u0e35\u0e19\u0e32\u0e16 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35\u0e1e\u0e31\u0e19\u0e1b\u0e35\u0e2b\u0e25\u0e27\u0e07 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 27 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21 2568 \u0e40\u0e27\u0e25\u0e32 09.15 &#8211; 10.00 \u0e19. \u0e14\u0e23.\u0e2d\u0e23\u0e2d\u0e38\u0e1a\u0e25 \u0e0a\u0e21\u0e40\u0e14\u0e0a \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e02\u0e2d\u0e07\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e2f \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e19\u0e49\u0e2d\u0e21\u0e16\u0e27\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e32\u0e25\u0e31\u0e22 \u0e41\u0e14\u0e48\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e19\u0e32\u0e07\u0e40\u0e08\u0e49\u0e32 \u0e2a\u0e34\u0e23\u0e34\u0e01\u0e34\u0e15\u0e34\u0e4c \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e34\u0e19\u0e35\u0e19\u0e32\u0e16 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35\u0e1e\u0e31\u0e19\u0e1b\u0e35\u0e2b\u0e25\u0e27\u0e07 \u0e17\u0e35\u0e48\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e41\u0e2a\u0e19 \u0e08\u0e31\u0e14\u0e02\u0e36\u0e49\u0e19 \u0e13 \u0e25\u0e32\u0e19\u0e40\u0e2d\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u0e0a\u0e31\u0e49\u0e19 1 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2b\u0e25\u0e27\u0e07\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e27\u0e32\u0e08\u0e01\u0e01\u0e2a\u0e34\u0e01\u0e34\u0e08 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e41\u0e2a\u0e19 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e19\u0e35\u0e49 \u0e23\u0e28.\u0e19.\u0e2a\u0e1e.\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e0a\u0e31\u0e22 \u0e20\u0e34\u0e0d\u0e42\u0e0d\u0e20\u0e39\u0e21\u0e34\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e23\u0e2d\u0e07\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e41\u0e2a\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e43\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e23\u0e32\u0e1a\u0e16\u0e27\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e32\u0e25\u0e31\u0e22 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e48\u0e27\u0e19\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e19\u0e34\u0e2a\u0e34\u0e15 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e1e\u0e23\u0e35\u0e22\u0e07\u0e01\u0e31\u0e19\u0e23\u0e48\u0e27\u0e21\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e32\u0e25\u0e31\u0e22 \u0e22\u0e37\u0e19\u0e2a\u0e07\u0e1a\u0e19\u0e34\u0e48\u0e07\u0e19\u0e49\u0e2d\u0e21\u0e23\u0e33\u0e25\u0e36\u0e01\u0e43\u0e19\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e32\u0e01\u0e23\u0e38\u0e13\u0e32\u0e18\u0e34\u0e04\u0e38\u0e13\u0e2d\u0e31\u0e19\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e21\u0e34\u0e44\u0e14\u0e49 \u0e41\u0e25\u0e30\u0e25\u0e07\u0e19\u0e32\u0e21\u0e16\u0e27\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e32\u0e25\u0e31\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e1e\u0e23\u0e30\u0e09\u0e32\u0e22\u0e32\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/cabnews\/27102025-a-memorial-service-for-her-majesty-queen-sirikit-the-queen-mother\/\" \/>\n<meta property=\"og:site_name\" content=\"cab.ku\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-27T14:22:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-24T14:29:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-content\/uploads\/2026\/03\/DSC01020.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"aomadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"aomadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/cabnews\/27102025-a-memorial-service-for-her-majesty-queen-sirikit-the-queen-mother\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/cabnews\/27102025-a-memorial-service-for-her-majesty-queen-sirikit-the-queen-mother\/\"},\"author\":{\"name\":\"aomadmin\",\"@id\":\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/#\/schema\/person\/3e14e85aa5eecda56c3271edf7f8e1c5\"},\"headline\":\"\u0e1e\u0e34\u0e18\u0e35\u0e19\u0e49\u0e2d\u0e21\u0e16\u0e27\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e32\u0e25\u0e31\u0e22 \u0e41\u0e14\u0e48\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e19\u0e32\u0e07\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e01\u0e34\u0e15\u0e34\u0e4c \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e34\u0e19\u0e35\u0e19\u0e32\u0e16 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35\u0e1e\u0e31\u0e19\u0e1b\u0e35\u0e2b\u0e25\u0e27\u0e07\",\"datePublished\":\"2025-10-27T14:22:00+00:00\",\"dateModified\":\"2026-03-24T14:29:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/cabnews\/27102025-a-memorial-service-for-her-majesty-queen-sirikit-the-queen-mother\/\"},\"wordCount\":1,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/cabnews\/27102025-a-memorial-service-for-her-majesty-queen-sirikit-the-queen-mother\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-content\/uploads\/2026\/03\/DSC01020.jpg\",\"articleSection\":[\"\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e17\u0e34\u0e14\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\",\"\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/cabnews\/27102025-a-memorial-service-for-her-majesty-queen-sirikit-the-queen-mother\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/cabnews\/27102025-a-memorial-service-for-her-majesty-queen-sirikit-the-queen-mother\/\",\"url\":\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/cabnews\/27102025-a-memorial-service-for-her-majesty-queen-sirikit-the-queen-mother\/\",\"name\":\"\u0e1e\u0e34\u0e18\u0e35\u0e19\u0e49\u0e2d\u0e21\u0e16\u0e27\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e32\u0e25\u0e31\u0e22 \u0e41\u0e14\u0e48\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e19\u0e32\u0e07\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e01\u0e34\u0e15\u0e34\u0e4c \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e34\u0e19\u0e35\u0e19\u0e32\u0e16 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35\u0e1e\u0e31\u0e19\u0e1b\u0e35\u0e2b\u0e25\u0e27\u0e07 - cab.ku\",\"isPartOf\":{\"@id\":\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/cabnews\/27102025-a-memorial-service-for-her-majesty-queen-sirikit-the-queen-mother\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/cabnews\/27102025-a-memorial-service-for-her-majesty-queen-sirikit-the-queen-mother\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-content\/uploads\/2026\/03\/DSC01020.jpg\",\"datePublished\":\"2025-10-27T14:22:00+00:00\",\"dateModified\":\"2026-03-24T14:29:42+00:00\",\"author\":{\"@id\":\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/#\/schema\/person\/3e14e85aa5eecda56c3271edf7f8e1c5\"},\"breadcrumb\":{\"@id\":\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/cabnews\/27102025-a-memorial-service-for-her-majesty-queen-sirikit-the-queen-mother\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/cabnews\/27102025-a-memorial-service-for-her-majesty-queen-sirikit-the-queen-mother\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/cabnews\/27102025-a-memorial-service-for-her-majesty-queen-sirikit-the-queen-mother\/#primaryimage\",\"url\":\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-content\/uploads\/2026\/03\/DSC01020.jpg\",\"contentUrl\":\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-content\/uploads\/2026\/03\/DSC01020.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/cabnews\/27102025-a-memorial-service-for-her-majesty-queen-sirikit-the-queen-mother\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e1e\u0e34\u0e18\u0e35\u0e19\u0e49\u0e2d\u0e21\u0e16\u0e27\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e32\u0e25\u0e31\u0e22 \u0e41\u0e14\u0e48\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e19\u0e32\u0e07\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e01\u0e34\u0e15\u0e34\u0e4c \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e34\u0e19\u0e35\u0e19\u0e32\u0e16 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35\u0e1e\u0e31\u0e19\u0e1b\u0e35\u0e2b\u0e25\u0e27\u0e07\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/#website\",\"url\":\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/\",\"name\":\"cab.ku\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/#\/schema\/person\/3e14e85aa5eecda56c3271edf7f8e1c5\",\"name\":\"aomadmin\",\"sameAs\":[\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\"],\"url\":\"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/author\/aomadmin\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0e1e\u0e34\u0e18\u0e35\u0e19\u0e49\u0e2d\u0e21\u0e16\u0e27\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e32\u0e25\u0e31\u0e22 \u0e41\u0e14\u0e48\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e19\u0e32\u0e07\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e01\u0e34\u0e15\u0e34\u0e4c \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e34\u0e19\u0e35\u0e19\u0e32\u0e16 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35\u0e1e\u0e31\u0e19\u0e1b\u0e35\u0e2b\u0e25\u0e27\u0e07 - cab.ku","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/cabnews\/27102025-a-memorial-service-for-her-majesty-queen-sirikit-the-queen-mother\/","og_locale":"en_US","og_type":"article","og_title":"\u0e1e\u0e34\u0e18\u0e35\u0e19\u0e49\u0e2d\u0e21\u0e16\u0e27\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e32\u0e25\u0e31\u0e22 \u0e41\u0e14\u0e48\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e19\u0e32\u0e07\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e01\u0e34\u0e15\u0e34\u0e4c \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e34\u0e19\u0e35\u0e19\u0e32\u0e16 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35\u0e1e\u0e31\u0e19\u0e1b\u0e35\u0e2b\u0e25\u0e27\u0e07","og_description":"\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e19\u0e49\u0e2d\u0e21\u0e16\u0e27\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e32\u0e25\u0e31\u0e22\u0e41\u0e14\u0e48 \u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e19\u0e32\u0e07\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e01\u0e34\u0e15\u0e34\u0e4c \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e34\u0e19\u0e35\u0e19\u0e32\u0e16 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35\u0e1e\u0e31\u0e19\u0e1b\u0e35\u0e2b\u0e25\u0e27\u0e07 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 27 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21 2568 \u0e40\u0e27\u0e25\u0e32 09.15 &#8211; 10.00 \u0e19. \u0e14\u0e23.\u0e2d\u0e23\u0e2d\u0e38\u0e1a\u0e25 \u0e0a\u0e21\u0e40\u0e14\u0e0a \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e02\u0e2d\u0e07\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e2f \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e19\u0e49\u0e2d\u0e21\u0e16\u0e27\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e32\u0e25\u0e31\u0e22 \u0e41\u0e14\u0e48\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e19\u0e32\u0e07\u0e40\u0e08\u0e49\u0e32 \u0e2a\u0e34\u0e23\u0e34\u0e01\u0e34\u0e15\u0e34\u0e4c \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e34\u0e19\u0e35\u0e19\u0e32\u0e16 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35\u0e1e\u0e31\u0e19\u0e1b\u0e35\u0e2b\u0e25\u0e27\u0e07 \u0e17\u0e35\u0e48\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e41\u0e2a\u0e19 \u0e08\u0e31\u0e14\u0e02\u0e36\u0e49\u0e19 \u0e13 \u0e25\u0e32\u0e19\u0e40\u0e2d\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u0e0a\u0e31\u0e49\u0e19 1 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2b\u0e25\u0e27\u0e07\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e27\u0e32\u0e08\u0e01\u0e01\u0e2a\u0e34\u0e01\u0e34\u0e08 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e41\u0e2a\u0e19 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e19\u0e35\u0e49 \u0e23\u0e28.\u0e19.\u0e2a\u0e1e.\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e0a\u0e31\u0e22 \u0e20\u0e34\u0e0d\u0e42\u0e0d\u0e20\u0e39\u0e21\u0e34\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e23\u0e2d\u0e07\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e41\u0e2a\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e43\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e23\u0e32\u0e1a\u0e16\u0e27\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e32\u0e25\u0e31\u0e22 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e48\u0e27\u0e19\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e19\u0e34\u0e2a\u0e34\u0e15 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e1e\u0e23\u0e35\u0e22\u0e07\u0e01\u0e31\u0e19\u0e23\u0e48\u0e27\u0e21\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e32\u0e25\u0e31\u0e22 \u0e22\u0e37\u0e19\u0e2a\u0e07\u0e1a\u0e19\u0e34\u0e48\u0e07\u0e19\u0e49\u0e2d\u0e21\u0e23\u0e33\u0e25\u0e36\u0e01\u0e43\u0e19\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e32\u0e01\u0e23\u0e38\u0e13\u0e32\u0e18\u0e34\u0e04\u0e38\u0e13\u0e2d\u0e31\u0e19\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e21\u0e34\u0e44\u0e14\u0e49 \u0e41\u0e25\u0e30\u0e25\u0e07\u0e19\u0e32\u0e21\u0e16\u0e27\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e32\u0e25\u0e31\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e1e\u0e23\u0e30\u0e09\u0e32\u0e22\u0e32\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u00a0","og_url":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/cabnews\/27102025-a-memorial-service-for-her-majesty-queen-sirikit-the-queen-mother\/","og_site_name":"cab.ku","article_published_time":"2025-10-27T14:22:00+00:00","article_modified_time":"2026-03-24T14:29:42+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-content\/uploads\/2026\/03\/DSC01020.jpg","type":"image\/jpeg"}],"author":"aomadmin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"aomadmin","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/cabnews\/27102025-a-memorial-service-for-her-majesty-queen-sirikit-the-queen-mother\/#article","isPartOf":{"@id":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/cabnews\/27102025-a-memorial-service-for-her-majesty-queen-sirikit-the-queen-mother\/"},"author":{"name":"aomadmin","@id":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/#\/schema\/person\/3e14e85aa5eecda56c3271edf7f8e1c5"},"headline":"\u0e1e\u0e34\u0e18\u0e35\u0e19\u0e49\u0e2d\u0e21\u0e16\u0e27\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e32\u0e25\u0e31\u0e22 \u0e41\u0e14\u0e48\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e19\u0e32\u0e07\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e01\u0e34\u0e15\u0e34\u0e4c \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e34\u0e19\u0e35\u0e19\u0e32\u0e16 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35\u0e1e\u0e31\u0e19\u0e1b\u0e35\u0e2b\u0e25\u0e27\u0e07","datePublished":"2025-10-27T14:22:00+00:00","dateModified":"2026-03-24T14:29:42+00:00","mainEntityOfPage":{"@id":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/cabnews\/27102025-a-memorial-service-for-her-majesty-queen-sirikit-the-queen-mother\/"},"wordCount":1,"commentCount":0,"image":{"@id":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/cabnews\/27102025-a-memorial-service-for-her-majesty-queen-sirikit-the-queen-mother\/#primaryimage"},"thumbnailUrl":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-content\/uploads\/2026\/03\/DSC01020.jpg","articleSection":["\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e17\u0e34\u0e14\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34","\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cab-dev.kps.ku.ac.th\/cabku\/cabnews\/27102025-a-memorial-service-for-her-majesty-queen-sirikit-the-queen-mother\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/cabnews\/27102025-a-memorial-service-for-her-majesty-queen-sirikit-the-queen-mother\/","url":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/cabnews\/27102025-a-memorial-service-for-her-majesty-queen-sirikit-the-queen-mother\/","name":"\u0e1e\u0e34\u0e18\u0e35\u0e19\u0e49\u0e2d\u0e21\u0e16\u0e27\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e32\u0e25\u0e31\u0e22 \u0e41\u0e14\u0e48\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e19\u0e32\u0e07\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e01\u0e34\u0e15\u0e34\u0e4c \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e34\u0e19\u0e35\u0e19\u0e32\u0e16 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35\u0e1e\u0e31\u0e19\u0e1b\u0e35\u0e2b\u0e25\u0e27\u0e07 - cab.ku","isPartOf":{"@id":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/cabnews\/27102025-a-memorial-service-for-her-majesty-queen-sirikit-the-queen-mother\/#primaryimage"},"image":{"@id":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/cabnews\/27102025-a-memorial-service-for-her-majesty-queen-sirikit-the-queen-mother\/#primaryimage"},"thumbnailUrl":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-content\/uploads\/2026\/03\/DSC01020.jpg","datePublished":"2025-10-27T14:22:00+00:00","dateModified":"2026-03-24T14:29:42+00:00","author":{"@id":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/#\/schema\/person\/3e14e85aa5eecda56c3271edf7f8e1c5"},"breadcrumb":{"@id":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/cabnews\/27102025-a-memorial-service-for-her-majesty-queen-sirikit-the-queen-mother\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cab-dev.kps.ku.ac.th\/cabku\/cabnews\/27102025-a-memorial-service-for-her-majesty-queen-sirikit-the-queen-mother\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/cabnews\/27102025-a-memorial-service-for-her-majesty-queen-sirikit-the-queen-mother\/#primaryimage","url":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-content\/uploads\/2026\/03\/DSC01020.jpg","contentUrl":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-content\/uploads\/2026\/03\/DSC01020.jpg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/cabnews\/27102025-a-memorial-service-for-her-majesty-queen-sirikit-the-queen-mother\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/"},{"@type":"ListItem","position":2,"name":"\u0e1e\u0e34\u0e18\u0e35\u0e19\u0e49\u0e2d\u0e21\u0e16\u0e27\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e32\u0e25\u0e31\u0e22 \u0e41\u0e14\u0e48\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e19\u0e32\u0e07\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e01\u0e34\u0e15\u0e34\u0e4c \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e34\u0e19\u0e35\u0e19\u0e32\u0e16 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35\u0e1e\u0e31\u0e19\u0e1b\u0e35\u0e2b\u0e25\u0e27\u0e07"}]},{"@type":"WebSite","@id":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/#website","url":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/","name":"cab.ku","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/#\/schema\/person\/3e14e85aa5eecda56c3271edf7f8e1c5","name":"aomadmin","sameAs":["https:\/\/cab-dev.kps.ku.ac.th\/cabku"],"url":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/author\/aomadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-json\/wp\/v2\/posts\/2530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-json\/wp\/v2\/comments?post=2530"}],"version-history":[{"count":0,"href":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-json\/wp\/v2\/posts\/2530\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-json\/wp\/v2\/media\/2541"}],"wp:attachment":[{"href":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-json\/wp\/v2\/media?parent=2530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-json\/wp\/v2\/categories?post=2530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cab-dev.kps.ku.ac.th\/cabku\/wp-json\/wp\/v2\/tags?post=2530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}